{"id":8385,"date":"2022-03-24T13:04:20","date_gmt":"2022-03-24T13:04:20","guid":{"rendered":"https:\/\/medexs.com\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/"},"modified":"2025-05-16T11:29:03","modified_gmt":"2025-05-16T11:29:03","slug":"haaglanden-medisch-centrum-westeinde","status":"publish","type":"portfolio","link":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/","title":{"rendered":"Haaglanden Medisch Centrum Westeinde"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":22,"featured_media":0,"parent":0,"template":"","categories":[],"class_list":["post-8385","portfolio","type-portfolio","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Haaglanden Medisch Centrum Westeinde - Medexs<\/title>\n<meta name=\"description\" content=\"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haaglanden Medisch Centrum Westeinde - Medexs\" \/>\n<meta property=\"og:description\" content=\"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/\" \/>\n<meta property=\"og:site_name\" content=\"Medexs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/daiwahousemodulareurope\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-16T11:29:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/\"},\"author\":{\"name\":\"Purdey Horbach\",\"@id\":\"https:\\\/\\\/medexs.com\\\/#\\\/schema\\\/person\\\/74fba8fc181fbbb00e6fb89ef9f68d91\"},\"headline\":\"Haaglanden Medisch Centrum Westeinde\",\"datePublished\":\"2022-03-24T13:04:20+00:00\",\"dateModified\":\"2025-05-16T11:29:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/\"},\"wordCount\":4,\"inLanguage\":\"en-US\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/\",\"url\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/\",\"name\":\"Haaglanden Medisch Centrum Westeinde - Medexs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medexs.com\\\/#website\"},\"datePublished\":\"2022-03-24T13:04:20+00:00\",\"dateModified\":\"2025-05-16T11:29:03+00:00\",\"description\":\"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medexs.com\\\/en\\\/portfolio-overzicht\\\/haaglanden-medisch-centrum-westeinde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medexs.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Haaglanden Medisch Centrum Westeinde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medexs.com\\\/#website\",\"url\":\"https:\\\/\\\/medexs.com\\\/\",\"name\":\"Medexs\",\"description\":\"Specialist in classified buildings and spaces\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medexs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medexs.com\\\/#\\\/schema\\\/person\\\/74fba8fc181fbbb00e6fb89ef9f68d91\",\"name\":\"Purdey Horbach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g\",\"caption\":\"Purdey Horbach\"},\"url\":\"https:\\\/\\\/medexs.com\\\/en\\\/author\\\/p-horbachmedexs-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haaglanden Medisch Centrum Westeinde - Medexs","description":"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/","og_locale":"en_US","og_type":"article","og_title":"Haaglanden Medisch Centrum Westeinde - Medexs","og_description":"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...","og_url":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/","og_site_name":"Medexs","article_publisher":"https:\/\/www.facebook.com\/daiwahousemodulareurope","article_modified_time":"2025-05-16T11:29:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/#article","isPartOf":{"@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/"},"author":{"name":"Purdey Horbach","@id":"https:\/\/medexs.com\/#\/schema\/person\/74fba8fc181fbbb00e6fb89ef9f68d91"},"headline":"Haaglanden Medisch Centrum Westeinde","datePublished":"2022-03-24T13:04:20+00:00","dateModified":"2025-05-16T11:29:03+00:00","mainEntityOfPage":{"@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/"},"wordCount":4,"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/","url":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/","name":"Haaglanden Medisch Centrum Westeinde - Medexs","isPartOf":{"@id":"https:\/\/medexs.com\/#website"},"datePublished":"2022-03-24T13:04:20+00:00","dateModified":"2025-05-16T11:29:03+00:00","description":"We carried out various activities for the expansion of the OR complex at the Westeinde location. Read more...","breadcrumb":{"@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medexs.com\/en\/portfolio-overzicht\/haaglanden-medisch-centrum-westeinde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medexs.com\/en\/"},{"@type":"ListItem","position":2,"name":"Haaglanden Medisch Centrum Westeinde"}]},{"@type":"WebSite","@id":"https:\/\/medexs.com\/#website","url":"https:\/\/medexs.com\/","name":"Medexs","description":"Specialist in classified buildings and spaces","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medexs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/medexs.com\/#\/schema\/person\/74fba8fc181fbbb00e6fb89ef9f68d91","name":"Purdey Horbach","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6098c1d124c979c4c7db9e934d051ae0c588b01b1a78faf547b5dc2c09d813d4?s=96&d=mm&r=g","caption":"Purdey Horbach"},"url":"https:\/\/medexs.com\/en\/author\/p-horbachmedexs-com\/"}]}},"_links":{"self":[{"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/portfolio\/8385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/users\/22"}],"wp:attachment":[{"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/media?parent=8385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medexs.com\/en\/wp-json\/wp\/v2\/categories?post=8385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}